{"id":2799,"date":"2020-11-09T10:51:11","date_gmt":"2020-11-09T10:51:11","guid":{"rendered":"http:\/\/wordpress.hotel-zedernhof.de\/?p=2799"},"modified":"2020-11-09T10:54:31","modified_gmt":"2020-11-09T10:54:31","slug":"brauchtumsveranstaltungen","status":"publish","type":"post","link":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/","title":{"rendered":"Brauchtumsveranstaltungen"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"2799\" class=\"elementor elementor-2799\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-365d38b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"365d38b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4dbb4cc\" data-id=\"4dbb4cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cbd4bf elementor-widget elementor-widget-image\" data-id=\"3cbd4bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1.jpg\" class=\"attachment-large size-large wp-image-2802\" alt=\"\" srcset=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1.jpg 1000w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1-300x180.jpg 300w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1-768x461.jpg 768w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1-16x10.jpg 16w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1-440x264.jpg 440w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum1-600x360.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88cba3e\" data-id=\"88cba3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b977808 elementor-widget elementor-widget-text-editor\" data-id=\"b977808\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Seit vielen Jahren, inzwischen schon wieder Tradition, gibt die Stamsrieder Blasmusik am Ostersonntag ein Fr\u00fchlingskonzert und stellt dabei ihr K\u00f6nnen unter Beweis.<\/p><p>Am letzten Tag im April wird zum ersten Mal im Jahr der Marktplatz f\u00fcr den Verkehr gesperrt. Das ist deshalb n\u00f6tig, weil dann der mit Kr\u00e4nzen und bunten B\u00e4ndern geschm\u00fcckte Maibaum angefahren und mitten auf dem Marktplatz nur mit Muskelkraft aufgestellt wird. Mit dabei die Stamsrieder Blasmusik und unsere Volkstanzgruppe.<\/p><p>Jedes Jahr wieder ein pr\u00e4chtiges Bild, wenn die Fronleichnamsprozession durch den festlich geschm\u00fcckten Ort zieht.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9e42486 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9e42486\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3fe6bac\" data-id=\"3fe6bac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-559f85e elementor-widget elementor-widget-image-gallery\" data-id=\"559f85e\" data-element_type=\"widget\" data-widget_type=\"image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-gallery\">\n\t\t\t\n\t\t<style type=\"text\/css\">\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 25%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-2799 gallery-columns-4 gallery-size-thumbnail'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"559f85e\" data-elementor-lightbox-title=\"bilderleiste4[b600] (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNCwidXJsIjoiaHR0cHM6XC9cL2hvdGVsLXplZGVybmhvZi5kZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTFcL2JpbGRlcmxlaXN0ZTRiNjAwLTItMS5qcGciLCJzbGlkZXNob3ciOiI1NTlmODVlIn0%3D\" href='https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste4b600-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste4b600-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste4b600-2-1-150x150.jpg 150w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste4b600-2-1-300x300.jpg 300w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste4b600-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"559f85e\" data-elementor-lightbox-title=\"bilderleiste3[b600] (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNSwidXJsIjoiaHR0cHM6XC9cL2hvdGVsLXplZGVybmhvZi5kZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTFcL2JpbGRlcmxlaXN0ZTNiNjAwLTItMS5qcGciLCJzbGlkZXNob3ciOiI1NTlmODVlIn0%3D\" href='https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste3b600-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste3b600-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste3b600-2-1-150x150.jpg 150w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste3b600-2-1-300x300.jpg 300w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste3b600-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"559f85e\" data-elementor-lightbox-title=\"bilderleiste2[b600] (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNiwidXJsIjoiaHR0cHM6XC9cL2hvdGVsLXplZGVybmhvZi5kZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTFcL2JpbGRlcmxlaXN0ZTJiNjAwLTItMS5qcGciLCJzbGlkZXNob3ciOiI1NTlmODVlIn0%3D\" href='https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste2b600-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste2b600-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste2b600-2-1-150x150.jpg 150w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste2b600-2-1-300x300.jpg 300w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste2b600-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"559f85e\" data-elementor-lightbox-title=\"bilderleiste1[b600] (2)\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjgwNywidXJsIjoiaHR0cHM6XC9cL2hvdGVsLXplZGVybmhvZi5kZVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyMFwvMTFcL2JpbGRlcmxlaXN0ZTFiNjAwLTItMS5qcGciLCJzbGlkZXNob3ciOiI1NTlmODVlIn0%3D\" href='https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste1b600-2-1.jpg'><img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste1b600-2-1-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste1b600-2-1-150x150.jpg 150w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste1b600-2-1-300x300.jpg 300w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/bilderleiste1b600-2-1-100x100.jpg 100w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d17c3e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d17c3e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42336e4\" data-id=\"42336e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-224a659 elementor-widget elementor-widget-text-editor\" data-id=\"224a659\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Kirchweih oder wie der Bayer sagt \u201eKirta\u201c wird bei uns am Sonntag nach \u201eJohanni\u201c gro\u00df gefeiert. Der Marktplatz wird f\u00fcr den Verkehr gesperrt. Um Speisen und Getr\u00e4nke k\u00fcmmern sich die \u00f6rtlichen Vereine. Diese sorgen auch mit Spielen, Spa\u00df und Unterhaltung daf\u00fcr, dass keine Langeweile aufkommen kann. F\u00fcr die musikalische Unterhaltung ist die Stamsrieder Blasmusik zust\u00e4ndig. Meist rundet ein Flohmarkt das Programm ab.<\/p><p>Ein weiterer, inzwischen schon zum Brauchtum z\u00e4hlender H\u00f6hepunkt im Veranstaltungsjahr, ist der \u201eAdvent im Schlosspark\u201c. Es gibt sicherlich weit und breit kein romantischeres Ambiente f\u00fcr solch eine Veranstaltung wie den Park.<\/p><p>Letzter H\u00f6hepunkt, Jahresabschluss auf dem Marktplatz, mit w\u00e4rmenden Getr\u00e4nken, Schmankerln und fetziger Musik von der \u201eCharly M\u201c Band.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fd00af5\" data-id=\"fd00af5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1664ad0 elementor-widget elementor-widget-image\" data-id=\"1664ad0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"600\" src=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2.jpg\" class=\"attachment-large size-large wp-image-2808\" alt=\"\" srcset=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2.jpg 1000w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2-300x180.jpg 300w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2-768x461.jpg 768w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2-16x10.jpg 16w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2-440x264.jpg 440w, https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum2-600x360.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Seit vielen Jahren, inzwischen schon wieder Tradition, gibt die Stamsrieder Blasmusik am Ostersonntag ein Fr\u00fchlingskonzert und stellt dabei ihr K\u00f6nnen unter Beweis. Am letzten Tag im April wird zum ersten Mal im Jahr der Marktplatz f\u00fcr den Verkehr gesperrt. Das [&hellip;]<\/p>","protected":false},"author":2,"featured_media":2800,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[143],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brauchtumsveranstaltungen - Hotel Zedernhof<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brauchtumsveranstaltungen - Hotel Zedernhof\" \/>\n<meta property=\"og:description\" content=\"Seit vielen Jahren, inzwischen schon wieder Tradition, gibt die Stamsrieder Blasmusik am Ostersonntag ein Fr\u00fchlingskonzert und stellt dabei ihr K\u00f6nnen unter Beweis. Am letzten Tag im April wird zum ersten Mal im Jahr der Marktplatz f\u00fcr den Verkehr gesperrt. Das [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Hotel Zedernhof\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-09T10:51:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-09T10:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum-top.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"clam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"clam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/\",\"url\":\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/\",\"name\":\"Brauchtumsveranstaltungen - Hotel Zedernhof\",\"isPartOf\":{\"@id\":\"https:\/\/hotel-zedernhof.de\/#website\"},\"datePublished\":\"2020-11-09T10:51:11+00:00\",\"dateModified\":\"2020-11-09T10:54:31+00:00\",\"author\":{\"@id\":\"https:\/\/hotel-zedernhof.de\/#\/schema\/person\/619883954c13db27f6d767b55f8e839c\"},\"breadcrumb\":{\"@id\":\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/hotel-zedernhof.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brauchtumsveranstaltungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hotel-zedernhof.de\/#website\",\"url\":\"https:\/\/hotel-zedernhof.de\/\",\"name\":\"Hotel Zedernhof\",\"description\":\"Hotel Zedernhof\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hotel-zedernhof.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/hotel-zedernhof.de\/#\/schema\/person\/619883954c13db27f6d767b55f8e839c\",\"name\":\"clam\",\"url\":\"https:\/\/hotel-zedernhof.de\/en\/author\/clam\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brauchtumsveranstaltungen - Hotel Zedernhof","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/","og_locale":"en_GB","og_type":"article","og_title":"Brauchtumsveranstaltungen - Hotel Zedernhof","og_description":"Seit vielen Jahren, inzwischen schon wieder Tradition, gibt die Stamsrieder Blasmusik am Ostersonntag ein Fr\u00fchlingskonzert und stellt dabei ihr K\u00f6nnen unter Beweis. Am letzten Tag im April wird zum ersten Mal im Jahr der Marktplatz f\u00fcr den Verkehr gesperrt. Das [&hellip;]","og_url":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/","og_site_name":"Hotel Zedernhof","article_published_time":"2020-11-09T10:51:11+00:00","article_modified_time":"2020-11-09T10:54:31+00:00","og_image":[{"width":2000,"height":1080,"url":"https:\/\/hotel-zedernhof.de\/wp-content\/uploads\/2020\/11\/brauchtum-top.jpg","type":"image\/jpeg"}],"author":"clam","twitter_card":"summary_large_image","twitter_misc":{"Written by":"clam","Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/","url":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/","name":"Brauchtumsveranstaltungen - Hotel Zedernhof","isPartOf":{"@id":"https:\/\/hotel-zedernhof.de\/#website"},"datePublished":"2020-11-09T10:51:11+00:00","dateModified":"2020-11-09T10:54:31+00:00","author":{"@id":"https:\/\/hotel-zedernhof.de\/#\/schema\/person\/619883954c13db27f6d767b55f8e839c"},"breadcrumb":{"@id":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hotel-zedernhof.de\/en\/sehenswertes-in-um-stamsried\/brauchtumsveranstaltungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hotel-zedernhof.de\/"},{"@type":"ListItem","position":2,"name":"Brauchtumsveranstaltungen"}]},{"@type":"WebSite","@id":"https:\/\/hotel-zedernhof.de\/#website","url":"https:\/\/hotel-zedernhof.de\/","name":"Hotel Zedernhof","description":"Hotel Zedernhof","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel-zedernhof.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/hotel-zedernhof.de\/#\/schema\/person\/619883954c13db27f6d767b55f8e839c","name":"clam","url":"https:\/\/hotel-zedernhof.de\/en\/author\/clam\/"}]}},"_links":{"self":[{"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/posts\/2799"}],"collection":[{"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/comments?post=2799"}],"version-history":[{"count":3,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/posts\/2799\/revisions"}],"predecessor-version":[{"id":2809,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/posts\/2799\/revisions\/2809"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/media\/2800"}],"wp:attachment":[{"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/media?parent=2799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/categories?post=2799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hotel-zedernhof.de\/en\/wp-json\/wp\/v2\/tags?post=2799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}